{"id":5816,"date":"2022-02-15T13:04:07","date_gmt":"2022-02-15T16:04:07","guid":{"rendered":"https:\/\/www.guiafacilbrasil.com.br\/blog\/?p=5816"},"modified":"2022-02-15T13:06:40","modified_gmt":"2022-02-15T16:06:40","slug":"bomba-dono-do-cruzeiro-e-idolo-da-selecao-ronaldo-fenomeno-pode-ser-preso-entenda","status":"publish","type":"post","link":"https:\/\/www.guiafacilbrasil.com.br\/blog\/bomba-dono-do-cruzeiro-e-idolo-da-selecao-ronaldo-fenomeno-pode-ser-preso-entenda\/","title":{"rendered":"BOMBA: Dono do Cruzeiro e \u00eddolo da Sele\u00e7\u00e3o, Ronaldo Fen\u00f4meno pode ser preso; ENTENDA"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-5821\" src=\"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/02\/Ronaldo-Fenomeno-1-300x185.png\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/02\/Ronaldo-Fenomeno-1-300x185.png 300w, https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/02\/Ronaldo-Fenomeno-1.png 613w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Ronaldo Fen\u00f4meno, craque da Sele\u00e7\u00e3o e dono do Cruzeiro, pode ser preso por atrasar o pagamento da pens\u00e3o aliment\u00edcia de seu filho Alex, de 16 anos. A m\u00e3e do garoto, Michele Umezu, entrou com a\u00e7\u00e3o na Justi\u00e7a para receber os valores devidos pelo ex-atleta.<\/p>\n<p>De acordo com informa\u00e7\u00f5es do portal \u201cUai\u201d, a advogada de Michele j\u00e1 entrou com pedido de pris\u00e3o contra o ex-craque da Sele\u00e7\u00e3o e, caso a pend\u00eancia permane\u00e7a, o jogador pode ser preso. Em entrevista, a representante da m\u00e3e de Alex afirmou ainda que Ronaldo \u201cn\u00e3o paga a pens\u00e3o desde dezembro\u201d e que isso teria acontecido porque Alex, seu filho, n\u00e3o quis passar o natal com o dono do Cruzeiro.<\/p>\n<p>Ainda segundo a advogada de Michele, ao portal \u201cUai\u201d, o \u00eddolo brasileiro tem tr\u00eas dias para pagar as pend\u00eancias ou justificar a falta de pagamento da pens\u00e3o aliment\u00edcia. Ela afirma que \u00e9 dif\u00edcil que o jogador seja preso, mas que \u201c\u00e9 uma vergonha chegar nesse n\u00edvel\u201d. \u201cO cara comprando um time de futebol inteiro e n\u00e3o pagar a pens\u00e3o do filho\u201d, afirmou a representante da m\u00e3e de Alex, segundo filho de Ronaldo.<\/p>\n<p><ins class=\"adsbygoogle adsbygoogle-noablate\" data-ad-type=\"text\" data-native-settings-key=\"ecb8e277\" data-ad-client=\"ca-pub-1867025325766476\" data-adsbygoogle-status=\"done\" data-ad-status=\"filled\"><ins id=\"aswift_4_expand\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><ins id=\"aswift_4_anchor\"><iframe loading=\"lazy\" id=\"aswift_4\" src=\"https:\/\/googleads.g.doubleclick.net\/pagead\/ads?client=ca-pub-1867025325766476&amp;output=html&amp;h=138&amp;adk=2718030622&amp;adf=3467895649&amp;pi=t.aa~a.2924529895~rp.4&amp;w=848&amp;lmt=1644838461&amp;nsk=ecb8e277&amp;rafmt=11&amp;pwprc=9922718127&amp;psa=1&amp;ad_type=text_image&amp;format=848x138&amp;url=https%3A%2F%2Fwww.guiafacilbrasil.com.br%2Fresultado%2Findex%3Fbuscar%3Dmedicos&amp;flash=0&amp;pra=3&amp;wgl=1&amp;fa=26&amp;adsid=ChAIgJiokAYQlJus8pn-hNIwEjsAivgvQtxPxu7DAMl0gY9767JkTfI-2r2KuMs0UFqo_W4HZiEuxkff4IIf1cNs7yhWC2xNJ2TiNhGNmA&amp;dt=1644838461537&amp;bpp=6&amp;bdt=2285&amp;idt=-M&amp;shv=r20220209&amp;mjsv=m202202080101&amp;ptt=9&amp;saldr=aa&amp;abxe=1&amp;cookie=ID%3D0621047bed327b6a-22b3c1ed18ba00a1%3AT%3D1623183136%3ART%3D1623183136%3AS%3DALNI_MaQfy3mTxI7_DB_f9g_xnHVKxStvQ&amp;prev_fmts=0x0%2C263x600&amp;nras=2&amp;correlator=8078107646141&amp;frm=20&amp;pv=1&amp;ga_vid=349506726.1623183140&amp;ga_sid=1644838460&amp;ga_hid=1802260653&amp;ga_fc=1&amp;u_tz=-180&amp;u_his=2&amp;u_h=900&amp;u_w=1600&amp;u_ah=860&amp;u_aw=1600&amp;u_cd=24&amp;u_sd=1&amp;adx=222&amp;ady=1409&amp;biw=1583&amp;bih=775&amp;scr_x=0&amp;scr_y=510&amp;eid=42531398%2C31064825%2C31063221&amp;oid=2&amp;psts=AGkb-H8MQKrs7daSuWZgTZaN7l1_QvnvWOZgbkk3Xd-z5DLzw1wlgmVHvXyHaKfEeMTBrs-782J6f8_sWeM&amp;pvsid=4019378836737187&amp;pem=24&amp;tmod=866476981&amp;nvt=1&amp;ref=https%3A%2F%2Fwww.guiafacilbrasil.com.br%2F&amp;eae=0&amp;fc=1792&amp;brdim=-8%2C-8%2C-8%2C-8%2C1600%2C0%2C1616%2C876%2C1600%2C775&amp;vis=1&amp;rsz=%7C%7Cs%7C&amp;abl=NS&amp;fu=128&amp;bc=31&amp;jar=2022-02-03-12&amp;ifi=5&amp;uci=a!5&amp;btvi=2&amp;fsb=1&amp;xpc=sqsijENVrX&amp;p=https%3A\/\/www.guiafacilbrasil.com.br&amp;dtd=37\" name=\"aswift_4\" width=\"848\" height=\"138\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-forms allow-popups allow-popups-to-escape-sandbox allow-same-origin allow-scripts allow-top-navigation-by-user-activation\" allowfullscreen=\"allowfullscreen\" data-google-container-id=\"a!5\" data-google-query-id=\"CPOh3uCM__UCFcYmrQYdRi0D2w\" data-load-complete=\"true\" data-mce-fragment=\"1\"><\/iframe><\/ins><\/ins><\/ins><\/p>\n<p>Terrabrasil \u2013\u00a0<a href=\"http:\/\/Guiafacilbrasil.com.br\/blog\/\"> Guiafacilbrasil.com.br\/blog<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ronaldo Fen\u00f4meno, craque da Sele\u00e7\u00e3o e dono do Cruzeiro, pode ser preso por atrasar o pagamento da pens\u00e3o aliment\u00edcia de seu filho Alex, de 16 anos. A m\u00e3e do garoto, Michele Umezu, entrou com a\u00e7\u00e3o na Justi\u00e7a para receber os valores devidos pelo ex-atleta. De acordo com informa\u00e7\u00f5es do portal \u201cUai\u201d, a advogada de Michele [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5821,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"_links":{"self":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/5816"}],"collection":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5816"}],"version-history":[{"count":3,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/5816\/revisions"}],"predecessor-version":[{"id":5822,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/5816\/revisions\/5822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/media\/5821"}],"wp:attachment":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}