{"id":5539,"date":"2022-02-04T09:03:22","date_gmt":"2022-02-04T12:03:22","guid":{"rendered":"https:\/\/www.guiafacilbrasil.com.br\/blog\/?p=5539"},"modified":"2022-02-04T09:03:32","modified_gmt":"2022-02-04T12:03:32","slug":"ex-delegado-de-patos-de-minas-morre-em-frente-a-santa-casa-de-misericordia","status":"publish","type":"post","link":"https:\/\/www.guiafacilbrasil.com.br\/blog\/ex-delegado-de-patos-de-minas-morre-em-frente-a-santa-casa-de-misericordia\/","title":{"rendered":"Ex-delegado de Patos de Minas morre em frente a Santa Casa de Miseric\u00f3rdia"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-5540\" src=\"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/02\/Ex-Delagado-300x233.png\" alt=\"\" width=\"300\" height=\"233\" srcset=\"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/02\/Ex-Delagado-300x233.png 300w, https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/02\/Ex-Delagado.png 762w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h3>Possivelmente v\u00edtima de infarto, Marcio Siqueira teve o \u00f3bito constatado pelo Samu<\/h3>\n<p>Morreu no in\u00edcio da madrugada desta sexta-feira (4\/2), Marcio Siqueira ex-delegado de Patos de Minas. O vel\u00f3rio est\u00e1 previsto para ocorrer de 12h \u00e0s 13h30 na funer\u00e1ria Bom Pastor, com sepultamento em Belo Horizonte.<\/p>\n<p>A Pol\u00edcia Militar foi acionada por volta de 0h40, com relatos de que um homem estava em frente a Santa Casa de Miseric\u00f3rdia aparentado estar passando mal, ao lado de um ve\u00edculo. Um bombeiro militar realizou procedimentos de reanima\u00e7\u00e3o com massagens card\u00edacas na v\u00edtima e acionou o atendimento m\u00e9dico do Samu. No entanto, os socorristas nada mais puderam fazer, constatando o \u00f3bito.<\/p>\n<p>Testemunhas afirmaram que o ex-delegado possu\u00eda problemas card\u00edacos e utilizada stents nas art\u00e9rias. Ainda conforme a pol\u00edcia, n\u00e3o foram encontrados sinais de viol\u00eancia no corpo.<\/p>\n<div>\n<div>\n<div>\n<div class=\"google-auto-placed\"><ins class=\"adsbygoogle adsbygoogle-noablate\" data-ad-type=\"text\" data-native-settings-key=\"cee47a9d\" data-ad-client=\"ca-pub-1867025325766476\" data-adsbygoogle-status=\"done\" data-ad-status=\"filled\"><ins id=\"aswift_4_expand\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><ins id=\"aswift_4_anchor\"><iframe loading=\"lazy\" id=\"aswift_4\" src=\"https:\/\/googleads.g.doubleclick.net\/pagead\/ads?client=ca-pub-1867025325766476&amp;output=html&amp;h=146&amp;adk=3612097632&amp;adf=3152942352&amp;pi=t.aa~a.2924541132~rp.4&amp;w=848&amp;lmt=1641555789&amp;nsk=cee47a9d&amp;rafmt=11&amp;pwprc=9922718127&amp;psa=1&amp;ad_type=text_image&amp;format=848x146&amp;url=https%3A%2F%2Fwww.guiafacilbrasil.com.br%2Fresultado%2Findex%3Fbuscar%3Dmedicos&amp;flash=0&amp;pra=3&amp;wgl=1&amp;fa=26&amp;dt=1641555789022&amp;bpp=2&amp;bdt=1551&amp;idt=-M&amp;shv=r20220104&amp;mjsv=m202112060101&amp;ptt=9&amp;saldr=aa&amp;abxe=1&amp;cookie=ID%3D0621047bed327b6a-22b3c1ed18ba00a1%3AT%3D1623183136%3ART%3D1623183136%3AS%3DALNI_MaQfy3mTxI7_DB_f9g_xnHVKxStvQ&amp;prev_fmts=0x0%2C263x600&amp;nras=2&amp;correlator=5145589493761&amp;frm=20&amp;pv=1&amp;ga_vid=349506726.1623183140&amp;ga_sid=1641555788&amp;ga_hid=1677957963&amp;ga_fc=1&amp;u_tz=-180&amp;u_his=2&amp;u_h=900&amp;u_w=1600&amp;u_ah=860&amp;u_aw=1600&amp;u_cd=24&amp;u_sd=1&amp;adx=222&amp;ady=1435&amp;biw=1583&amp;bih=775&amp;scr_x=0&amp;scr_y=510&amp;eid=31062423&amp;oid=2&amp;pvsid=2418394369484656&amp;pem=24&amp;tmod=830&amp;ref=https%3A%2F%2Fwww.guiafacilbrasil.com.br%2F&amp;eae=0&amp;fc=1792&amp;brdim=-8%2C-8%2C-8%2C-8%2C1600%2C0%2C1616%2C876%2C1600%2C775&amp;vis=1&amp;rsz=%7C%7Cs%7C&amp;abl=NS&amp;fu=128&amp;bc=31&amp;ifi=5&amp;uci=a!5&amp;btvi=2&amp;fsb=1&amp;xpc=9Co5iGRO3q&amp;p=https%3A\/\/www.guiafacilbrasil.com.br&amp;dtd=116\" name=\"aswift_4\" width=\"848\" height=\"146\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-forms allow-popups allow-popups-to-escape-sandbox allow-same-origin allow-scripts allow-top-navigation-by-user-activation\" allowfullscreen=\"allowfullscreen\" data-google-container-id=\"a!5\" data-google-query-id=\"CLyo_-jHn_UCFT8EigMdzEoCbA\" data-load-complete=\"true\" data-mce-fragment=\"1\"><\/iframe><\/ins><\/ins><\/ins><\/div>\n<div>Patos j\u00e1 \u2013\u00a0<a href=\"http:\/\/Guiafacilbrasil.com.br\/blog\/\"> Guiafacilbrasil.com.br\/blog<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Possivelmente v\u00edtima de infarto, Marcio Siqueira teve o \u00f3bito constatado pelo Samu Morreu no in\u00edcio da madrugada desta sexta-feira (4\/2), Marcio Siqueira ex-delegado de Patos de Minas. O vel\u00f3rio est\u00e1 previsto para ocorrer de 12h \u00e0s 13h30 na funer\u00e1ria Bom Pastor, com sepultamento em Belo Horizonte. A Pol\u00edcia Militar foi acionada por volta de 0h40, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5540,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/5539"}],"collection":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5539"}],"version-history":[{"count":1,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/5539\/revisions"}],"predecessor-version":[{"id":5541,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/5539\/revisions\/5541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/media\/5540"}],"wp:attachment":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}