{"id":20854,"date":"2024-04-26T09:20:35","date_gmt":"2024-04-26T12:20:35","guid":{"rendered":"https:\/\/www.guiafacilbrasil.com.br\/blog\/?p=20854"},"modified":"2024-04-26T09:20:35","modified_gmt":"2024-04-26T12:20:35","slug":"auxilio-alimentacao-do-funcionalismo-publico-vai-ter-aumento-de-mais-de-50","status":"publish","type":"post","link":"https:\/\/www.guiafacilbrasil.com.br\/blog\/auxilio-alimentacao-do-funcionalismo-publico-vai-ter-aumento-de-mais-de-50\/","title":{"rendered":"Aux\u00edlio-alimenta\u00e7\u00e3o do funcionalismo p\u00fablico vai ter aumento de mais de 50%"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-20855\" src=\"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2024\/04\/Auxilio-alimentacao-do-funcionalismo-publico-vai-ter-aumento-de-mais-de-50-300x149.png\" alt=\"\" width=\"300\" height=\"149\" srcset=\"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2024\/04\/Auxilio-alimentacao-do-funcionalismo-publico-vai-ter-aumento-de-mais-de-50-300x149.png 300w, https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2024\/04\/Auxilio-alimentacao-do-funcionalismo-publico-vai-ter-aumento-de-mais-de-50.png 521w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Jo\u00e9dson Alves\/Ag\u00eancia Brasil<\/p>\n<p>A partir do pr\u00f3ximo m\u00eas, os servidores p\u00fablicos federais receber\u00e3o um aumento de <strong>51,9%<\/strong> no aux\u00edlio-alimenta\u00e7\u00e3o, elevando o valor de <strong>R$ 658<\/strong> para <strong>R$ 1.000<\/strong>. O aux\u00edlio-sa\u00fade tamb\u00e9m ser\u00e1 ajustado de <strong>R$ 144,38<\/strong> para aproximadamente <strong>R$ 215<\/strong>, enquanto o aux\u00edlio-creche subir\u00e1 de <strong>R$ 321<\/strong> para <strong>R$ 484,90<\/strong>.<\/p>\n<p>Este acordo foi selado na quinta-feira, 25 de abril de 2024, entre representantes dos servidores e o governo federal, atrav\u00e9s da SRT\/MGI. O governo se comprometeu a implementar at\u00e9 julho todas as negocia\u00e7\u00f5es de carreiras espec\u00edficas pendentes na Mesa Nacional de Negocia\u00e7\u00e3o Permanente.<\/p>\n<p>Segundo o minist\u00e9rio, o refor\u00e7o no aux\u00edlio-alimenta\u00e7\u00e3o representa um aumento de renda superior a <strong>4,5%<\/strong> para mais de <strong>200 mil<\/strong> servidores ativos que recebem at\u00e9 <strong>R$ 9.000<\/strong> mensais. Aqueles com menores sal\u00e1rios e que recebem os tr\u00eas benef\u00edcios simultaneamente podem ver um aumento de at\u00e9 <strong>23%<\/strong> em sua remunera\u00e7\u00e3o total.<\/p>\n<p>Jos\u00e9 Lopez Feij\u00f3o, secret\u00e1rio de Rela\u00e7\u00f5es do Trabalho do MGI, mencionou que em 2023 j\u00e1 houve um aumento salarial linear para todos os servidores federais. Ele destacou que o acordo atual, somado ao reajuste de <strong>9%<\/strong> do ano anterior, inicia a recupera\u00e7\u00e3o dos sal\u00e1rios que estavam congelados por muito tempo.<\/p>\n<p>A Condsef considerou o aumento dos benef\u00edcios positivo, mas continuar\u00e1 a lutar por um reajuste salarial de <strong>7% a 10%<\/strong> ainda este ano. S\u00e9rgio Ronaldo da Silva, secret\u00e1rio-geral da Condsef, expressou que, apesar de n\u00e3o haver garantias de aumento para 2024, a entidade n\u00e3o desistir\u00e1 da reivindica\u00e7\u00e3o hist\u00f3rica de recupera\u00e7\u00e3o do poder de compra dos servidores, especialmente ap\u00f3s o per\u00edodo de congelamento salarial do governo anterior.<\/p>\n<p>A Condsef representa <strong>80%<\/strong> dos servidores do Executivo Federal, incluindo ativos, aposentados e pensionistas.<\/p>\n<div class=\"code-block code-block-5 code-block-content-4\">\n<div>\n<div>Essas informa\u00e7\u00f5es s\u00e3o cortesia da Ag\u00eancia Brasil.<\/div>\n<div>\n<p>&nbsp;<\/p>\n<div>\n<div class=\"google-auto-placed\">\n<div id=\"aswift_3_host\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><iframe loading=\"lazy\" id=\"aswift_3\" src=\"https:\/\/googleads.g.doubleclick.net\/pagead\/ads?gdpr=0&amp;client=ca-pub-1867025325766476&amp;output=html&amp;h=90&amp;adk=1701493149&amp;adf=616662408&amp;pi=t.aa~a.2924540085~rp.4&amp;w=848&amp;fwrn=1&amp;fwrnh=100&amp;lmt=1709813013&amp;rafmt=1&amp;to=qs&amp;pwprc=9922718127&amp;format=848x90&amp;url=https%3A%2F%2Fwww.guiafacilbrasil.com.br%2Fresultado%2Findex%3Fbuscar%3Dmedicos&amp;fwr=0&amp;fwrattr=false&amp;pra=3&amp;rpe=1&amp;resp_fmts=3&amp;wgl=1&amp;fa=40&amp;dt=1709813013356&amp;bpp=1&amp;bdt=1293&amp;idt=-M&amp;shv=r20240305&amp;mjsv=m202402290101&amp;ptt=9&amp;saldr=aa&amp;abxe=1&amp;cookie=ID%3D82a5025d674ba57f%3AT%3D1704806387%3ART%3D1709813007%3AS%3DALNI_MbYJCio4xXHPTEJqImOmFmvbCpOlg&amp;gpic=UID%3D00000db59b2d0105%3AT%3D1704806387%3ART%3D1709813007%3AS%3DALNI_MZShTHob1uAe5rzlxgQJyIVFrjNCw&amp;eo_id_str=ID%3Dfab46bc442db0ddb%3AT%3D1706618080%3ART%3D1709813007%3AS%3DAA-AfjZw_dD9ZCaMIrQOz880LATa&amp;prev_fmts=0x0%2C263x600%2C1005x124&amp;nras=3&amp;correlator=2961628183303&amp;frm=20&amp;pv=1&amp;ga_vid=1841769769.1704806387&amp;ga_sid=1709813013&amp;ga_hid=550791955&amp;ga_fc=1&amp;u_tz=-180&amp;u_his=4&amp;u_h=900&amp;u_w=1600&amp;u_ah=860&amp;u_aw=1600&amp;u_cd=24&amp;u_sd=1&amp;adx=222&amp;ady=1062&amp;biw=1583&amp;bih=775&amp;scr_x=0&amp;scr_y=682&amp;eid=44759876%2C44759927%2C44759842%2C31081613%2C44798934%2C95325753%2C95322181%2C95324161%2C95325784%2C95326431%2C95326936&amp;oid=2&amp;psts=AOrYGsmG2aXE3xx85cxBuRQSznx91Bw6iSzFqzcHvIiTaBGwcb7Of7G_epWSLocPsQdcvKIFelsxqw8wiZL6goAitBc842nn-RHagtCK0J2Vies9SIb_9g&amp;pvsid=3209576149461143&amp;tmod=445440623&amp;uas=0&amp;nvt=1&amp;ref=https%3A%2F%2Fwww.guiafacilbrasil.com.br%2Fresultado%2Findex%3Fbuscar%3Dmedcios&amp;fc=1920&amp;brdim=-8%2C-8%2C-8%2C-8%2C1600%2C0%2C1616%2C876%2C1600%2C775&amp;vis=1&amp;rsz=%7C%7Cs%7C&amp;abl=NS&amp;fu=128&amp;bc=31&amp;bz=1.01&amp;ifi=4&amp;uci=a!4&amp;fsb=1&amp;dtd=141\" name=\"aswift_3\" width=\"848\" height=\"90\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-forms allow-popups allow-popups-to-escape-sandbox allow-same-origin allow-scripts allow-top-navigation-by-user-activation\" data-google-container-id=\"a!4\" data-load-complete=\"true\" data-google-query-id=\"CKfk3-qN4oQDFXuM7gEdHXAHLA\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<div class=\"panel panel-default painel-estabeleciment \">\n<div class=\"row\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 TerraBrasil \u2013 <a href=\"http:\/\/guiafacilbrasil.com.br\/blog\/\">\u00a0GuiaF\u00e1cilBrasil<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jo\u00e9dson Alves\/Ag\u00eancia Brasil A partir do pr\u00f3ximo m\u00eas, os servidores p\u00fablicos federais receber\u00e3o um aumento de 51,9% no aux\u00edlio-alimenta\u00e7\u00e3o, elevando o valor de R$ 658 para R$ 1.000. O aux\u00edlio-sa\u00fade tamb\u00e9m ser\u00e1 ajustado de R$ 144,38 para aproximadamente R$ 215, enquanto o aux\u00edlio-creche subir\u00e1 de R$ 321 para R$ 484,90. Este acordo foi selado na [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20855,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[25],"tags":[],"_links":{"self":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/20854"}],"collection":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/comments?post=20854"}],"version-history":[{"count":1,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/20854\/revisions"}],"predecessor-version":[{"id":20856,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/20854\/revisions\/20856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/media\/20855"}],"wp:attachment":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/media?parent=20854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/categories?post=20854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/tags?post=20854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}