{"id":13175,"date":"2023-02-12T10:18:03","date_gmt":"2023-02-12T13:18:03","guid":{"rendered":"https:\/\/www.guiafacilbrasil.com.br\/blog\/?p=13175"},"modified":"2023-02-12T10:18:03","modified_gmt":"2023-02-12T13:18:03","slug":"bolsonaro-anuncia-volta-ao-brasil-minha-missao-nao-acabou","status":"publish","type":"post","link":"https:\/\/www.guiafacilbrasil.com.br\/blog\/bolsonaro-anuncia-volta-ao-brasil-minha-missao-nao-acabou\/","title":{"rendered":"Bolsonaro anuncia volta ao Brasil: \u201cMinha miss\u00e3o n\u00e3o acabou\u201d"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone  wp-image-13176\" src=\"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2023\/02\/Bolsonaro-anuncia-sua-volta-ao-Brasil-300x178.png\" alt=\"\" width=\"410\" height=\"243\" srcset=\"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2023\/02\/Bolsonaro-anuncia-sua-volta-ao-Brasil-300x178.png 300w, https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2023\/02\/Bolsonaro-anuncia-sua-volta-ao-Brasil.png 360w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/><\/p>\n<p>Foto: REUTERS\/Adriano Machado.<\/p>\n<p>Em evento com brasileiros na Fl\u00f3rida, o ex-presidente Jair Bolsonaro afirmou neste s\u00e1bado (11) que pretende voltar ao Brasil nas pr\u00f3ximas semanas e que sua \u201cmiss\u00e3o\u201d ainda n\u00e3o acabou.<\/p>\n<p>Durante o discurso, na igreja evang\u00e9lica Church of All Nations, Bolsonaro disse que n\u00e3o conseguiu se reeleger \u201cdiante do TSE\u201d e que pretende colaborar com a direita brasileira.<\/p>\n<p>\u201c\u00c9 uma satisfa\u00e7\u00e3o muito grande a forma que voc\u00eas t\u00eam me tratado em qualquer lugar desse globo. Isso n\u00e3o tem pre\u00e7o. Ainda mais para quem, pelo menos diante do TSE, n\u00e3o conseguiu se reeleger. Todos n\u00f3s temos uma miss\u00e3o aqui na Terra, a minha miss\u00e3o ainda n\u00e3o acabou. N\u00e3o interessa o que venha a acontecer comigo aqui ou no Brasil\u201d, afirmou.<\/p>\n<p>Sobre sua inten\u00e7\u00e3o de colaborar com a lideran\u00e7a da direita no pa\u00eds, ele disse:<\/p>\n<p>\u201cNo momento n\u00e3o temos uma lideran\u00e7a da direita nacional. Temos regional. Esse pessoal vai crescendo. N\u00f3s vamos nos fortalecer. N\u00f3s voltaremos. A nossa voca\u00e7\u00e3o \u00e9 ser mais que extens\u00e3o, na verdade, uma grande na\u00e7\u00e3o. Olha o que Israel n\u00e3o tem, e veja o que eles s\u00e3o. Olha o que n\u00f3s temos, e o que n\u00f3s n\u00e3o somos.\u201d<\/p>\n<p>O discurso foi feito para uma plateia de cerca de mil pessoas, de acordo com estimativa dos organizadores.<\/p>\n<p>Cr\u00e9ditos: O Antagonista.<\/p>\n<div>\n<div>\n<figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\">\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div class=\"wp-block-button is-style-3d\">\n<div>\n<div>\n<div>\n<div>\n<div>\n<div dir=\"ltr\">\n<div>\n<div id=\"aswift_3_host\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><iframe loading=\"lazy\" id=\"aswift_3\" src=\"https:\/\/googleads.g.doubleclick.net\/pagead\/ads?client=ca-pub-1867025325766476&amp;output=html&amp;h=280&amp;adk=2886104892&amp;adf=2229015579&amp;pi=t.aa~a.2924536900~rp.4&amp;w=848&amp;fwrn=4&amp;fwrnh=100&amp;lmt=1664796045&amp;rafmt=1&amp;to=qs&amp;pwprc=9922718127&amp;psa=1&amp;format=848x280&amp;url=https%3A%2F%2Fwww.guiafacilbrasil.com.br%2Fresultado%3Fbuscar%3Dmedicos%26page%3D4&amp;fwr=0&amp;pra=3&amp;rpe=1&amp;resp_fmts=3&amp;wgl=1&amp;fa=40&amp;dt=1664796045160&amp;bpp=4&amp;bdt=1396&amp;idt=-M&amp;shv=r20220928&amp;mjsv=m202209270101&amp;ptt=9&amp;saldr=aa&amp;abxe=1&amp;cookie=ID%3D7f4ab2fd29c398a0-22d262d1f17e0035%3AT%3D1663500202%3ART%3D1663500202%3AS%3DALNI_MYa-hAvjFB_7uPQKiM-G8CHc9Y1Kg&amp;gpic=UID%3D0000096c65e8b28b%3AT%3D1663500202%3ART%3D1664795401%3AS%3DALNI_Mb97AP82UDyK2n1otr9R9JK14bXKQ&amp;prev_fmts=0x0%2C263x600%2C1005x124&amp;nras=3&amp;correlator=8386473302186&amp;frm=20&amp;pv=1&amp;ga_vid=1874506523.1663500216&amp;ga_sid=1664796044&amp;ga_hid=1915970878&amp;ga_fc=1&amp;u_tz=-180&amp;u_his=7&amp;u_h=900&amp;u_w=1600&amp;u_ah=860&amp;u_aw=1600&amp;u_cd=24&amp;u_sd=1&amp;adx=222&amp;ady=1380&amp;biw=1583&amp;bih=775&amp;scr_x=0&amp;scr_y=510&amp;eid=44759876%2C44759927%2C44759837%2C42531705%2C44768832%2C31069993&amp;oid=2&amp;pvsid=3481426357853475&amp;tmod=1327846035&amp;nvt=1&amp;ref=https%3A%2F%2Fwww.guiafacilbrasil.com.br%2Fresultado%3Fbuscar%3Dmedicos%26page%3D3&amp;eae=0&amp;fc=1920&amp;brdim=-8%2C-8%2C-8%2C-8%2C1600%2C0%2C1616%2C876%2C1600%2C775&amp;vis=1&amp;rsz=%7C%7Cs%7C&amp;abl=NS&amp;fu=128&amp;bc=31&amp;ifi=4&amp;uci=a!4&amp;btvi=2&amp;fsb=1&amp;xpc=fUuUrPLpta&amp;p=https%3A\/\/www.guiafacilbrasil.com.br&amp;dtd=51\" name=\"aswift_3\" width=\"848\" height=\"280\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-forms allow-popups allow-popups-to-escape-sandbox allow-same-origin allow-scripts allow-top-navigation-by-user-activation\" data-google-container-id=\"a!4\" data-load-complete=\"true\" data-google-query-id=\"CJK5hMb4w_oCFVWw0QQd7f0BIA\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<div id=\"aswift_3_host\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><strong>TerraBrasil <\/strong>\u2013 <a href=\"http:\/\/Guiafacilbrasil.com.br\/blog\/\">\u00a0GuiaFacilBrasil.com.br\/blog<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foto: REUTERS\/Adriano Machado. Em evento com brasileiros na Fl\u00f3rida, o ex-presidente Jair Bolsonaro afirmou neste s\u00e1bado (11) que pretende voltar ao Brasil nas pr\u00f3ximas semanas e que sua \u201cmiss\u00e3o\u201d ainda n\u00e3o acabou. Durante o discurso, na igreja evang\u00e9lica Church of All Nations, Bolsonaro disse que n\u00e3o conseguiu se reeleger \u201cdiante do TSE\u201d e que pretende [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"_links":{"self":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/13175"}],"collection":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/comments?post=13175"}],"version-history":[{"count":1,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/13175\/revisions"}],"predecessor-version":[{"id":13177,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/13175\/revisions\/13177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/media\/13176"}],"wp:attachment":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/media?parent=13175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/categories?post=13175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/tags?post=13175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}