{"id":12089,"date":"2022-12-31T17:55:38","date_gmt":"2022-12-31T20:55:38","guid":{"rendered":"https:\/\/www.guiafacilbrasil.com.br\/blog\/?p=12089"},"modified":"2022-12-31T17:55:38","modified_gmt":"2022-12-31T20:55:38","slug":"apos-liberacao-da-justica-delegacao-de-maduro-chega-a-brasilia-para-posse-de-lula","status":"publish","type":"post","link":"https:\/\/www.guiafacilbrasil.com.br\/blog\/apos-liberacao-da-justica-delegacao-de-maduro-chega-a-brasilia-para-posse-de-lula\/","title":{"rendered":"Ap\u00f3s libera\u00e7\u00e3o da justi\u00e7a, delega\u00e7\u00e3o de Maduro chega a Bras\u00edlia para posse de Lula"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-12090\" src=\"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/12\/Delegacao-de-madura-chega-em-Brasilia-300x169.png\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/12\/Delegacao-de-madura-chega-em-Brasilia-300x169.png 300w, https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/12\/Delegacao-de-madura-chega-em-Brasilia.png 360w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Foto: Reprodu\u00e7\u00e3o.<\/p>\n<p>A comitiva venezuelana encarregada de preparar a vinda do ditador\u00a0<strong>Nicol\u00e1s Maduro<\/strong>\u00a0(foto) ao pa\u00eds para a cerim\u00f4nia de\u00a0<strong>posse de Lula<\/strong>\u00a0chegou a\u00a0<strong>Bras\u00edlia<\/strong>\u00a0neste s\u00e1bado (31). A delega\u00e7\u00e3o organiza quest\u00f5es de\u00a0<strong>seguran\u00e7a<\/strong>\u00a0e\u00a0<strong>infraestrutura<\/strong>.<\/p>\n<p>O\u00a0impedimento de ingresso no Brasil de altos funcion\u00e1rios do regime venezuelano, imposto por decis\u00e3o de 2019, foi derrubado na quinta-feira por decis\u00e3o dos\u00a0<strong>minist\u00e9rios da Justi\u00e7a e Seguran\u00e7a P\u00fablica e das Rela\u00e7\u00f5es Exteriores<\/strong>.<\/p>\n<p>A portaria interministerial que proibia a entrada foi\u00a0assinada por\u00a0<strong>Sergio <span id=\"IL_AD5\" class=\"IL_AD\">Moro<\/span><\/strong>\u00a0e\u00a0<strong><span id=\"IL_AD3\" class=\"IL_AD\">Ernesto<\/span> Ara\u00fajo<\/strong>, ent\u00e3o <span id=\"IL_AD4\" class=\"IL_AD\">ministros<\/span> da Justi\u00e7a e das Rela\u00e7\u00f5es Exteriores.\u00a0\u00a0<strong>A decis\u00e3o se escorou nas declara\u00e7\u00f5es do\u00a0<em>\u201cGrupo de Lima\u201d<\/em>,<\/strong>\u00a0que re\u00fane chanceleres de 12 pa\u00edses do <span id=\"IL_AD2\" class=\"IL_AD\">continente<\/span> <span id=\"IL_AD1\" class=\"IL_AD\">americano<\/span>.<\/p>\n<p>A\u00a0cerim\u00f4nia de posse de Lula, neste domingo (1\u00ba) contar\u00e1 com ao menos\u00a0<strong>65 delega\u00e7\u00f5es estrangeiras<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div class=\"wp-block-button is-style-3d\">\n<div>\n<div>\n<div>\n<div>\n<div>\n<div dir=\"ltr\">\n<div>\n<div id=\"aswift_3_host\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><iframe loading=\"lazy\" id=\"aswift_3\" src=\"https:\/\/googleads.g.doubleclick.net\/pagead\/ads?client=ca-pub-1867025325766476&amp;output=html&amp;h=280&amp;adk=2886104892&amp;adf=2229015579&amp;pi=t.aa~a.2924536900~rp.4&amp;w=848&amp;fwrn=4&amp;fwrnh=100&amp;lmt=1664796045&amp;rafmt=1&amp;to=qs&amp;pwprc=9922718127&amp;psa=1&amp;format=848x280&amp;url=https%3A%2F%2Fwww.guiafacilbrasil.com.br%2Fresultado%3Fbuscar%3Dmedicos%26page%3D4&amp;fwr=0&amp;pra=3&amp;rpe=1&amp;resp_fmts=3&amp;wgl=1&amp;fa=40&amp;dt=1664796045160&amp;bpp=4&amp;bdt=1396&amp;idt=-M&amp;shv=r20220928&amp;mjsv=m202209270101&amp;ptt=9&amp;saldr=aa&amp;abxe=1&amp;cookie=ID%3D7f4ab2fd29c398a0-22d262d1f17e0035%3AT%3D1663500202%3ART%3D1663500202%3AS%3DALNI_MYa-hAvjFB_7uPQKiM-G8CHc9Y1Kg&amp;gpic=UID%3D0000096c65e8b28b%3AT%3D1663500202%3ART%3D1664795401%3AS%3DALNI_Mb97AP82UDyK2n1otr9R9JK14bXKQ&amp;prev_fmts=0x0%2C263x600%2C1005x124&amp;nras=3&amp;correlator=8386473302186&amp;frm=20&amp;pv=1&amp;ga_vid=1874506523.1663500216&amp;ga_sid=1664796044&amp;ga_hid=1915970878&amp;ga_fc=1&amp;u_tz=-180&amp;u_his=7&amp;u_h=900&amp;u_w=1600&amp;u_ah=860&amp;u_aw=1600&amp;u_cd=24&amp;u_sd=1&amp;adx=222&amp;ady=1380&amp;biw=1583&amp;bih=775&amp;scr_x=0&amp;scr_y=510&amp;eid=44759876%2C44759927%2C44759837%2C42531705%2C44768832%2C31069993&amp;oid=2&amp;pvsid=3481426357853475&amp;tmod=1327846035&amp;nvt=1&amp;ref=https%3A%2F%2Fwww.guiafacilbrasil.com.br%2Fresultado%3Fbuscar%3Dmedicos%26page%3D3&amp;eae=0&amp;fc=1920&amp;brdim=-8%2C-8%2C-8%2C-8%2C1600%2C0%2C1616%2C876%2C1600%2C775&amp;vis=1&amp;rsz=%7C%7Cs%7C&amp;abl=NS&amp;fu=128&amp;bc=31&amp;ifi=4&amp;uci=a!4&amp;btvi=2&amp;fsb=1&amp;xpc=fUuUrPLpta&amp;p=https%3A\/\/www.guiafacilbrasil.com.br&amp;dtd=51\" name=\"aswift_3\" width=\"848\" height=\"280\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-forms allow-popups allow-popups-to-escape-sandbox allow-same-origin allow-scripts allow-top-navigation-by-user-activation\" data-google-container-id=\"a!4\" data-load-complete=\"true\" data-google-query-id=\"CJK5hMb4w_oCFVWw0QQd7f0BIA\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<div id=\"aswift_3_host\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><strong>TerraBrasil <\/strong>\u2013 <a href=\"http:\/\/Guiafacilbrasil.com.br\/blog\/\">\u00a0GuiaFacilBrasil.com.br\/blog<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Reprodu\u00e7\u00e3o. A comitiva venezuelana encarregada de preparar a vinda do ditador\u00a0Nicol\u00e1s Maduro\u00a0(foto) ao pa\u00eds para a cerim\u00f4nia de\u00a0posse de Lula\u00a0chegou a\u00a0Bras\u00edlia\u00a0neste s\u00e1bado (31). A delega\u00e7\u00e3o organiza quest\u00f5es de\u00a0seguran\u00e7a\u00a0e\u00a0infraestrutura. O\u00a0impedimento de ingresso no Brasil de altos funcion\u00e1rios do regime venezuelano, imposto por decis\u00e3o de 2019, foi derrubado na quinta-feira por decis\u00e3o dos\u00a0minist\u00e9rios da Justi\u00e7a e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12090,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/12089"}],"collection":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/comments?post=12089"}],"version-history":[{"count":1,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/12089\/revisions"}],"predecessor-version":[{"id":12091,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/12089\/revisions\/12091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/media\/12090"}],"wp:attachment":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/media?parent=12089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/categories?post=12089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/tags?post=12089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}