{"id":11039,"date":"2022-11-10T17:17:22","date_gmt":"2022-11-10T20:17:22","guid":{"rendered":"https:\/\/www.guiafacilbrasil.com.br\/blog\/?p=11039"},"modified":"2022-11-10T17:17:22","modified_gmt":"2022-11-10T20:17:22","slug":"moraes-pede-a-lula-projeto-para-regulamentar-as-plataformas-digitais","status":"publish","type":"post","link":"https:\/\/www.guiafacilbrasil.com.br\/blog\/moraes-pede-a-lula-projeto-para-regulamentar-as-plataformas-digitais\/","title":{"rendered":"Moraes pede a Lula projeto para regulamentar as plataformas digitais"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-11040\" src=\"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/11\/Moraes-e-Lula-300x202.png\" alt=\"\" width=\"300\" height=\"202\" srcset=\"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/11\/Moraes-e-Lula-300x202.png 300w, https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/11\/Moraes-e-Lula.png 449w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h4>Presidente do Tribunal Superior Eleitoral relatou os desafios no combate \u00e0s fake news e questionou impunidade de empresas como o Google<\/h4>\n<p>O presidente do Tribunal Superior Eleitoral (TSE), ministro\u00a0<strong>Alexandre de Moraes<\/strong>, fez um pedido especial ao presidente eleito\u00a0<strong>Lula<\/strong>\u00a0(PT) durante a visita de cortesia desta quarta-feira, 9.<\/p>\n<p>No encontro realizado no TSE, Moraes relatou o \u201ctrabalh\u00e3o\u201d que a Corte teve durante as elei\u00e7\u00f5es deste ano em decorr\u00eancia do que chamou de\u00a0<strong>ataques ao regime democr\u00e1tico<\/strong>\u00a0e ao estado de direito, e disse que o tribunal e a sociedade civil devem apresentar um anteprojeto (um estudo ou vers\u00e3o pr\u00e9via de uma proposta) para\u00a0<strong>regulamentar as plataformas digitais e combater as fake news<\/strong>. O ministro acrescentou que o texto deve ter aval do Executivo. \u201cFica o pedido\u201d, disse.<\/p>\n<p>Respons\u00e1vel pelo inqu\u00e9rito que apura a propaga\u00e7\u00e3o de not\u00edcias falsas \u2013 uma dor de cabe\u00e7a enorme para Jair Bolsonaro e seus apoiadores -, o ministro ressaltou que o tribunal fez uma resolu\u00e7\u00e3o espec\u00edfica de combate \u00e0 desinforma\u00e7\u00e3o que pode ajudar na elabora\u00e7\u00e3o desse projeto de lei. A norma a que fez men\u00e7\u00e3o foi aprovada dias antes do segundo turno das elei\u00e7\u00f5es, gerou uma s\u00e9rie de questionamentos e acabou judicializada no Superior Tribunal Federal, que manteve a resolu\u00e7\u00e3o. O\u00a0texto aumenta o \u201cpoder de pol\u00edcia\u201d\u00a0do TSE e traz uma s\u00e9rie de regramentos, entre os quais a proibi\u00e7\u00e3o da divulga\u00e7\u00e3o de fatos sabidamente inver\u00eddicos.<\/p>\n<p>Antes do pedido, Moraes lembrou as a\u00e7\u00f5es do TSE no combate \u00e0s\u00a0<em>fakes news<\/em>e ao discurso de \u00f3dio nos \u00faltimos tr\u00eas anos e apresentou um balan\u00e7o das medidas aplicadas antes das elei\u00e7\u00f5es \u2013 como, em 36 horas, a retirada de 1,8 milh\u00e3o de usu\u00e1rios do Telegram.<\/p>\n<p>\u201cN\u00e3o \u00e9 poss\u00edvel que essas plataformas sejam consideradas empresas de tecnologia e n\u00e3o de m\u00eddia. S\u00f3 o Google fatura 12 vezes mais que todo o sistema Globo e n\u00e3o punido \u00e9 em nada, como se nada ocorresse por l\u00e1\u201d, disse o presidente do TSE.<\/p>\n<p>Ap\u00f3s os apelos, a conversa seguiu, e Lula n\u00e3o comentou sobre os pedidos. Nesta quinta, 10, um dia depois do encontro, o presidente eleito fez uma s\u00e9rie de elogios ao presidente do TSE, a quem chamou de \u201chomem de comportamento exemplar\u201d e \u201corgulho de todo o Brasil\u201d.<\/p>\n<p>Veja<\/p>\n<div class=\"wp-block-button is-style-3d\">\n<div>\n<div>\n<div>\n<div>\n<div>\n<div dir=\"ltr\">\n<div>\n<div id=\"aswift_3_host\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><iframe loading=\"lazy\" id=\"aswift_3\" src=\"https:\/\/googleads.g.doubleclick.net\/pagead\/ads?client=ca-pub-1867025325766476&amp;output=html&amp;h=280&amp;adk=2886104892&amp;adf=2229015579&amp;pi=t.aa~a.2924536900~rp.4&amp;w=848&amp;fwrn=4&amp;fwrnh=100&amp;lmt=1664796045&amp;rafmt=1&amp;to=qs&amp;pwprc=9922718127&amp;psa=1&amp;format=848x280&amp;url=https%3A%2F%2Fwww.guiafacilbrasil.com.br%2Fresultado%3Fbuscar%3Dmedicos%26page%3D4&amp;fwr=0&amp;pra=3&amp;rpe=1&amp;resp_fmts=3&amp;wgl=1&amp;fa=40&amp;dt=1664796045160&amp;bpp=4&amp;bdt=1396&amp;idt=-M&amp;shv=r20220928&amp;mjsv=m202209270101&amp;ptt=9&amp;saldr=aa&amp;abxe=1&amp;cookie=ID%3D7f4ab2fd29c398a0-22d262d1f17e0035%3AT%3D1663500202%3ART%3D1663500202%3AS%3DALNI_MYa-hAvjFB_7uPQKiM-G8CHc9Y1Kg&amp;gpic=UID%3D0000096c65e8b28b%3AT%3D1663500202%3ART%3D1664795401%3AS%3DALNI_Mb97AP82UDyK2n1otr9R9JK14bXKQ&amp;prev_fmts=0x0%2C263x600%2C1005x124&amp;nras=3&amp;correlator=8386473302186&amp;frm=20&amp;pv=1&amp;ga_vid=1874506523.1663500216&amp;ga_sid=1664796044&amp;ga_hid=1915970878&amp;ga_fc=1&amp;u_tz=-180&amp;u_his=7&amp;u_h=900&amp;u_w=1600&amp;u_ah=860&amp;u_aw=1600&amp;u_cd=24&amp;u_sd=1&amp;adx=222&amp;ady=1380&amp;biw=1583&amp;bih=775&amp;scr_x=0&amp;scr_y=510&amp;eid=44759876%2C44759927%2C44759837%2C42531705%2C44768832%2C31069993&amp;oid=2&amp;pvsid=3481426357853475&amp;tmod=1327846035&amp;nvt=1&amp;ref=https%3A%2F%2Fwww.guiafacilbrasil.com.br%2Fresultado%3Fbuscar%3Dmedicos%26page%3D3&amp;eae=0&amp;fc=1920&amp;brdim=-8%2C-8%2C-8%2C-8%2C1600%2C0%2C1616%2C876%2C1600%2C775&amp;vis=1&amp;rsz=%7C%7Cs%7C&amp;abl=NS&amp;fu=128&amp;bc=31&amp;ifi=4&amp;uci=a!4&amp;btvi=2&amp;fsb=1&amp;xpc=fUuUrPLpta&amp;p=https%3A\/\/www.guiafacilbrasil.com.br&amp;dtd=51\" name=\"aswift_3\" width=\"848\" height=\"280\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-forms allow-popups allow-popups-to-escape-sandbox allow-same-origin allow-scripts allow-top-navigation-by-user-activation\" data-google-container-id=\"a!4\" data-load-complete=\"true\" data-google-query-id=\"CJK5hMb4w_oCFVWw0QQd7f0BIA\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<div id=\"aswift_3_host\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><strong>TerrraBrasil <\/strong>\u2013 <a href=\"http:\/\/Guiafacilbrasil.com.br\/blog\/\">\u00a0GuiaFacilBrasil.com.br\/blog<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Presidente do Tribunal Superior Eleitoral relatou os desafios no combate \u00e0s fake news e questionou impunidade de empresas como o Google O presidente do Tribunal Superior Eleitoral (TSE), ministro\u00a0Alexandre de Moraes, fez um pedido especial ao presidente eleito\u00a0Lula\u00a0(PT) durante a visita de cortesia desta quarta-feira, 9. No encontro realizado no TSE, Moraes relatou o \u201ctrabalh\u00e3o\u201d [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"_links":{"self":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/11039"}],"collection":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/comments?post=11039"}],"version-history":[{"count":1,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/11039\/revisions"}],"predecessor-version":[{"id":11041,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/11039\/revisions\/11041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/media\/11040"}],"wp:attachment":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/media?parent=11039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/categories?post=11039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/tags?post=11039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}