{"id":10994,"date":"2022-11-09T12:02:21","date_gmt":"2022-11-09T15:02:21","guid":{"rendered":"https:\/\/www.guiafacilbrasil.com.br\/blog\/?p=10994"},"modified":"2022-11-09T12:02:21","modified_gmt":"2022-11-09T15:02:21","slug":"gal-costa-morre-aos-77-anos","status":"publish","type":"post","link":"https:\/\/www.guiafacilbrasil.com.br\/blog\/gal-costa-morre-aos-77-anos\/","title":{"rendered":"Gal Costa morre aos 77 anos"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-10995\" src=\"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/11\/Gal-Costa-300x212.png\" alt=\"\" width=\"300\" height=\"212\" srcset=\"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/11\/Gal-Costa-300x212.png 300w, https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/11\/Gal-Costa.png 359w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Gal Costa morre aos 77 anos. A informa\u00e7\u00e3o foi confirmada pela assessoria da cantora.<\/p>\n<p>Gal havia dado uma pausa em shows, ap\u00f3s passar por uma cirurgia para retirar um n\u00f3dulo na fossa nasal direita.<\/p>\n<p>Bem recebido pelo p\u00fablico e pela cr\u00edtica, esse show fez com que a agenda de Gal ficasse agitada ap\u00f3s a pandemia. A estreia aconteceu em S\u00e3o Paulo, em outubro do ano passado.<\/p>\n<p>Al\u00e9m de rodar o Brasil, Gal entrou na programa\u00e7\u00e3o de v\u00e1rios festivais e ainda tinha uma turn\u00ea na Europa prevista para novembro, mas que tamb\u00e9m foi cancelada por conta da cirurgia.<\/p>\n<p>Ela estava em turn\u00ea com o show \u201cAs v\u00e1rias pontas de uma estrela\u201d, no qual revisitava grandes sucessos dos anos 80 do cancioneiro popular da MPB. \u201cA\u00e7a\u00ed\u201d, \u201cNada mais\u201d, \u201cSorte\u201d e \u201cLua de mel\u201d s\u00e3o algumas das m\u00fasicas do repert\u00f3rio.<\/p>\n<p>Bem recebido pelo p\u00fablico e pela cr\u00edtica, esse show fez com que a agenda de Gal ficasse agitada ap\u00f3s a pandemia. A estreia aconteceu em S\u00e3o Paulo, em outubro do ano passado.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"wp-block-button is-style-3d\">\n<div>\n<div>\n<div>\n<div>\n<div>\n<div dir=\"ltr\">\n<div>\n<div id=\"aswift_3_host\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><iframe loading=\"lazy\" id=\"aswift_3\" src=\"https:\/\/googleads.g.doubleclick.net\/pagead\/ads?client=ca-pub-1867025325766476&amp;output=html&amp;h=280&amp;adk=2886104892&amp;adf=2229015579&amp;pi=t.aa~a.2924536900~rp.4&amp;w=848&amp;fwrn=4&amp;fwrnh=100&amp;lmt=1664796045&amp;rafmt=1&amp;to=qs&amp;pwprc=9922718127&amp;psa=1&amp;format=848x280&amp;url=https%3A%2F%2Fwww.guiafacilbrasil.com.br%2Fresultado%3Fbuscar%3Dmedicos%26page%3D4&amp;fwr=0&amp;pra=3&amp;rpe=1&amp;resp_fmts=3&amp;wgl=1&amp;fa=40&amp;dt=1664796045160&amp;bpp=4&amp;bdt=1396&amp;idt=-M&amp;shv=r20220928&amp;mjsv=m202209270101&amp;ptt=9&amp;saldr=aa&amp;abxe=1&amp;cookie=ID%3D7f4ab2fd29c398a0-22d262d1f17e0035%3AT%3D1663500202%3ART%3D1663500202%3AS%3DALNI_MYa-hAvjFB_7uPQKiM-G8CHc9Y1Kg&amp;gpic=UID%3D0000096c65e8b28b%3AT%3D1663500202%3ART%3D1664795401%3AS%3DALNI_Mb97AP82UDyK2n1otr9R9JK14bXKQ&amp;prev_fmts=0x0%2C263x600%2C1005x124&amp;nras=3&amp;correlator=8386473302186&amp;frm=20&amp;pv=1&amp;ga_vid=1874506523.1663500216&amp;ga_sid=1664796044&amp;ga_hid=1915970878&amp;ga_fc=1&amp;u_tz=-180&amp;u_his=7&amp;u_h=900&amp;u_w=1600&amp;u_ah=860&amp;u_aw=1600&amp;u_cd=24&amp;u_sd=1&amp;adx=222&amp;ady=1380&amp;biw=1583&amp;bih=775&amp;scr_x=0&amp;scr_y=510&amp;eid=44759876%2C44759927%2C44759837%2C42531705%2C44768832%2C31069993&amp;oid=2&amp;pvsid=3481426357853475&amp;tmod=1327846035&amp;nvt=1&amp;ref=https%3A%2F%2Fwww.guiafacilbrasil.com.br%2Fresultado%3Fbuscar%3Dmedicos%26page%3D3&amp;eae=0&amp;fc=1920&amp;brdim=-8%2C-8%2C-8%2C-8%2C1600%2C0%2C1616%2C876%2C1600%2C775&amp;vis=1&amp;rsz=%7C%7Cs%7C&amp;abl=NS&amp;fu=128&amp;bc=31&amp;ifi=4&amp;uci=a!4&amp;btvi=2&amp;fsb=1&amp;xpc=fUuUrPLpta&amp;p=https%3A\/\/www.guiafacilbrasil.com.br&amp;dtd=51\" name=\"aswift_3\" width=\"848\" height=\"280\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-forms allow-popups allow-popups-to-escape-sandbox allow-same-origin allow-scripts allow-top-navigation-by-user-activation\" data-google-container-id=\"a!4\" data-load-complete=\"true\" data-google-query-id=\"CJK5hMb4w_oCFVWw0QQd7f0BIA\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<div id=\"aswift_3_host\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><strong>TerrraBrasil <\/strong>\u2013 <a href=\"http:\/\/Guiafacilbrasil.com.br\/blog\/\">\u00a0GuiaFacilBrasil.com.br\/blog<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gal Costa morre aos 77 anos. A informa\u00e7\u00e3o foi confirmada pela assessoria da cantora. Gal havia dado uma pausa em shows, ap\u00f3s passar por uma cirurgia para retirar um n\u00f3dulo na fossa nasal direita. Bem recebido pelo p\u00fablico e pela cr\u00edtica, esse show fez com que a agenda de Gal ficasse agitada ap\u00f3s a pandemia. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10995,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/10994"}],"collection":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/comments?post=10994"}],"version-history":[{"count":1,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/10994\/revisions"}],"predecessor-version":[{"id":10996,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/10994\/revisions\/10996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/media\/10995"}],"wp:attachment":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/media?parent=10994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/categories?post=10994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/tags?post=10994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}