{"id":10371,"date":"2022-10-15T09:53:39","date_gmt":"2022-10-15T12:53:39","guid":{"rendered":"https:\/\/www.guiafacilbrasil.com.br\/blog\/?p=10371"},"modified":"2022-10-15T09:53:39","modified_gmt":"2022-10-15T12:53:39","slug":"boato-toffoli-nao-assumiu-a-presidencia-do-tse-no-lugar-de-moraes","status":"publish","type":"post","link":"https:\/\/www.guiafacilbrasil.com.br\/blog\/boato-toffoli-nao-assumiu-a-presidencia-do-tse-no-lugar-de-moraes\/","title":{"rendered":"Boato: Toffoli n\u00e3o assumiu a Presid\u00eancia do TSE no lugar de Moraes"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-10372\" src=\"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/10\/Boatos-300x209.png\" alt=\"\" width=\"300\" height=\"209\" srcset=\"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/10\/Boatos-300x209.png 300w, https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-content\/uploads\/2022\/10\/Boatos.png 519w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Um v\u00eddeo com afirma\u00e7\u00e3o enganosa circula pelas redes sociais. As cenas foram gravadas na \u00faltima ter\u00e7a-feira (4) no gabinete da Presid\u00eancia do Tribunal Superior Eleitoral (TSE), quando o atual presidente, ministro Alexandre de Moraes, empossou o novo ministro substituto da Corte ministro Dias Toffoli.<\/p>\n<p>A afirma\u00e7\u00e3o que acompanha o v\u00eddeo \u00e9 inver\u00eddica: a\u00a0<em>fake news<\/em>\u00a0diz que Moraes passa o cargo de presidente para o ministro que acaba de tomar posse como substituto.<\/p>\n<p><strong>O que \u00e9 o cargo de ministro substituto?<\/strong><\/p>\n<p>Toffoli tomou posse no dia 4 de outubro como ministro substituto, que \u00e9 convocado para atuar apenas quando o titular do cargo n\u00e3o puder comparecer ou se declarar impedido de julgar determinado processo.<\/p>\n<p>O TSE \u00e9 composto por, no m\u00ednimo, sete ministros: tr\u00eas s\u00e3o origin\u00e1rios do STF, dois do Superior Tribunal de Justi\u00e7a (STJ) e dois s\u00e3o juristas \u2013 advogados com not\u00e1vel saber jur\u00eddico e idoneidade.<\/p>\n<p>De acordo com a regra estabelecida pela Constitui\u00e7\u00e3o Federal, para cada ministro titular, deve haver um substituto, ou seja, igual n\u00famero (sete) de ministros substitutos nas respectivas categorias.<\/p>\n<p>Hoje, comp\u00f5em o TSE nas vagas destinadas ao STF os ministros Alexandre de Moraes (presidente), Ricardo Lewandowski (vice-presidente) e C\u00e1rmen L\u00facia, nos cargos efetivos.\u00a0Os substitutos s\u00e3o os ministros Nunes Marques, Andr\u00e9 Mendon\u00e7a e Dias Toffoli, que s\u00e3o convocados para compor o Plen\u00e1rio no caso de aus\u00eancia dos titulares. No entanto, em eventual aus\u00eancia do presidente do TSE, assume a cadeira o vice-presidente, que hoje \u00e9 o ministro Lewandowski.<\/p>\n<p>Vale lembrar que o mandato do ministro Alexandre de Moraes como presidente do TSE termina dia 3 de junho de 2024.<\/p>\n<p>Confira a\u00a0<a href=\"https:\/\/www.tse.jus.br\/o-tse\/ministros\/apresentacao\">composi\u00e7\u00e3o atual<\/a>.<\/p>\n<p>Cr\u00e9ditos: Justi\u00e7a Eleitoral.<\/p>\n<div>\n<div id=\"aswift_3_host\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><iframe loading=\"lazy\" id=\"aswift_3\" src=\"https:\/\/googleads.g.doubleclick.net\/pagead\/ads?client=ca-pub-1867025325766476&amp;output=html&amp;h=280&amp;adk=2886104892&amp;adf=2229015579&amp;pi=t.aa~a.2924536900~rp.4&amp;w=848&amp;fwrn=4&amp;fwrnh=100&amp;lmt=1664796045&amp;rafmt=1&amp;to=qs&amp;pwprc=9922718127&amp;psa=1&amp;format=848x280&amp;url=https%3A%2F%2Fwww.guiafacilbrasil.com.br%2Fresultado%3Fbuscar%3Dmedicos%26page%3D4&amp;fwr=0&amp;pra=3&amp;rpe=1&amp;resp_fmts=3&amp;wgl=1&amp;fa=40&amp;dt=1664796045160&amp;bpp=4&amp;bdt=1396&amp;idt=-M&amp;shv=r20220928&amp;mjsv=m202209270101&amp;ptt=9&amp;saldr=aa&amp;abxe=1&amp;cookie=ID%3D7f4ab2fd29c398a0-22d262d1f17e0035%3AT%3D1663500202%3ART%3D1663500202%3AS%3DALNI_MYa-hAvjFB_7uPQKiM-G8CHc9Y1Kg&amp;gpic=UID%3D0000096c65e8b28b%3AT%3D1663500202%3ART%3D1664795401%3AS%3DALNI_Mb97AP82UDyK2n1otr9R9JK14bXKQ&amp;prev_fmts=0x0%2C263x600%2C1005x124&amp;nras=3&amp;correlator=8386473302186&amp;frm=20&amp;pv=1&amp;ga_vid=1874506523.1663500216&amp;ga_sid=1664796044&amp;ga_hid=1915970878&amp;ga_fc=1&amp;u_tz=-180&amp;u_his=7&amp;u_h=900&amp;u_w=1600&amp;u_ah=860&amp;u_aw=1600&amp;u_cd=24&amp;u_sd=1&amp;adx=222&amp;ady=1380&amp;biw=1583&amp;bih=775&amp;scr_x=0&amp;scr_y=510&amp;eid=44759876%2C44759927%2C44759837%2C42531705%2C44768832%2C31069993&amp;oid=2&amp;pvsid=3481426357853475&amp;tmod=1327846035&amp;nvt=1&amp;ref=https%3A%2F%2Fwww.guiafacilbrasil.com.br%2Fresultado%3Fbuscar%3Dmedicos%26page%3D3&amp;eae=0&amp;fc=1920&amp;brdim=-8%2C-8%2C-8%2C-8%2C1600%2C0%2C1616%2C876%2C1600%2C775&amp;vis=1&amp;rsz=%7C%7Cs%7C&amp;abl=NS&amp;fu=128&amp;bc=31&amp;ifi=4&amp;uci=a!4&amp;btvi=2&amp;fsb=1&amp;xpc=fUuUrPLpta&amp;p=https%3A\/\/www.guiafacilbrasil.com.br&amp;dtd=51\" name=\"aswift_3\" width=\"848\" height=\"280\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-forms allow-popups allow-popups-to-escape-sandbox allow-same-origin allow-scripts allow-top-navigation-by-user-activation\" data-google-container-id=\"a!4\" data-load-complete=\"true\" data-google-query-id=\"CJK5hMb4w_oCFVWw0QQd7f0BIA\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<div tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\">TerraBrasil\u00a0 \u2013 <a href=\"http:\/\/Guiafacilbrasil.com.br\/blog\/\">\u00a0GuiaFacilBrasil.com.br\/blog<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um v\u00eddeo com afirma\u00e7\u00e3o enganosa circula pelas redes sociais. As cenas foram gravadas na \u00faltima ter\u00e7a-feira (4) no gabinete da Presid\u00eancia do Tribunal Superior Eleitoral (TSE), quando o atual presidente, ministro Alexandre de Moraes, empossou o novo ministro substituto da Corte ministro Dias Toffoli. A afirma\u00e7\u00e3o que acompanha o v\u00eddeo \u00e9 inver\u00eddica: a\u00a0fake news\u00a0diz que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[27],"tags":[],"_links":{"self":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/10371"}],"collection":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/comments?post=10371"}],"version-history":[{"count":1,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/10371\/revisions"}],"predecessor-version":[{"id":10373,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/10371\/revisions\/10373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/media\/10372"}],"wp:attachment":[{"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/media?parent=10371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/categories?post=10371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.guiafacilbrasil.com.br\/blog\/wp-json\/wp\/v2\/tags?post=10371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}